{"id":28,"count":56,"description":"","link":"https:\/\/centre-stage.com\/home\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/centre-stage.com\/home\/wp-json\/wp\/v2\/categories\/28"}],"collection":[{"href":"https:\/\/centre-stage.com\/home\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/centre-stage.com\/home\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/centre-stage.com\/home\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}